{"id":6563,"date":"2026-07-17T15:17:49","date_gmt":"2026-07-17T19:17:49","guid":{"rendered":"https:\/\/www.squawka.com\/us-es\/stats\/players\/tijjani-reijnders\/"},"modified":"2026-07-17T15:17:49","modified_gmt":"2026-07-17T19:17:49","slug":"tijjani-reijnders","status":"publish","type":"player","link":"https:\/\/www.squawka.com\/us-es\/stats\/players\/tijjani-reijnders\/","title":{"rendered":"Tijjani Reijnders"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":3584,"featured_media":0,"template":"","meta":{"_acf_changed":false,"_yoast_wpseo_focuskw":"","_yoast_wpseo_title":"","_yoast_wpseo_metadesc":"","footnotes":""},"season":[368],"sports-type":[367],"country":[369],"event-competition":[],"class_list":["post-6563","player","type-player","status-publish","hentry"],"acf":{"external_featured_image_url":"","hide_featured_image_pattern":false},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Tijjani Reijnders - Squawka | US-ES<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.squawka.com\/us-es\/stats\/players\/tijjani-reijnders\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tijjani Reijnders\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.squawka.com\/us-es\/stats\/players\/tijjani-reijnders\/\" \/>\n<meta property=\"og:site_name\" content=\"Squawka | US-ES\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.squawka.com\\\/us-es\\\/stats\\\/players\\\/tijjani-reijnders\\\/\",\"url\":\"https:\\\/\\\/www.squawka.com\\\/us-es\\\/stats\\\/players\\\/tijjani-reijnders\\\/\",\"name\":\"Tijjani Reijnders - Squawka | US-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.squawka.com\\\/us-es\\\/#website\"},\"datePublished\":\"2026-07-17T19:17:49+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.squawka.com\\\/us-es\\\/stats\\\/players\\\/tijjani-reijnders\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.squawka.com\\\/us-es\\\/stats\\\/players\\\/tijjani-reijnders\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.squawka.com\\\/us-es\\\/stats\\\/players\\\/tijjani-reijnders\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Squawka\",\"item\":\"https:\\\/\\\/www.squawka.com\\\/us-es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Players\",\"item\":\"https:\\\/\\\/www.squawka.com\\\/us-es\\\/stats\\\/players\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Tijjani Reijnders\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.squawka.com\\\/us-es\\\/#website\",\"url\":\"https:\\\/\\\/www.squawka.com\\\/us-es\\\/\",\"name\":\"Squawka US-ES\",\"description\":\"F\u00fatbol con datos: noticias, estad\u00edsticas y pron\u00f3sticos\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.squawka.com\\\/us-es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Tijjani Reijnders - Squawka | US-ES","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.squawka.com\/us-es\/stats\/players\/tijjani-reijnders\/","og_locale":"es_MX","og_type":"article","og_title":"Tijjani Reijnders","og_url":"https:\/\/www.squawka.com\/us-es\/stats\/players\/tijjani-reijnders\/","og_site_name":"Squawka | US-ES","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.squawka.com\/us-es\/stats\/players\/tijjani-reijnders\/","url":"https:\/\/www.squawka.com\/us-es\/stats\/players\/tijjani-reijnders\/","name":"Tijjani Reijnders - Squawka | US-ES","isPartOf":{"@id":"https:\/\/www.squawka.com\/us-es\/#website"},"datePublished":"2026-07-17T19:17:49+00:00","breadcrumb":{"@id":"https:\/\/www.squawka.com\/us-es\/stats\/players\/tijjani-reijnders\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.squawka.com\/us-es\/stats\/players\/tijjani-reijnders\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.squawka.com\/us-es\/stats\/players\/tijjani-reijnders\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Squawka","item":"https:\/\/www.squawka.com\/us-es\/"},{"@type":"ListItem","position":2,"name":"Players","item":"https:\/\/www.squawka.com\/us-es\/stats\/players\/"},{"@type":"ListItem","position":3,"name":"Tijjani Reijnders"}]},{"@type":"WebSite","@id":"https:\/\/www.squawka.com\/us-es\/#website","url":"https:\/\/www.squawka.com\/us-es\/","name":"Squawka US-ES","description":"F\u00fatbol con datos: noticias, estad\u00edsticas y pron\u00f3sticos","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.squawka.com\/us-es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"core_id":"665db6c4e93e306d7f467845","yoast_title":"","yoast_description":"","yoast_keyword":"","_links":{"self":[{"href":"https:\/\/www.squawka.com\/us-es\/wp-json\/wp\/v2\/player\/6563","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.squawka.com\/us-es\/wp-json\/wp\/v2\/player"}],"about":[{"href":"https:\/\/www.squawka.com\/us-es\/wp-json\/wp\/v2\/types\/player"}],"author":[{"embeddable":true,"href":"https:\/\/www.squawka.com\/us-es\/wp-json\/wp\/v2\/users\/3584"}],"version-history":[{"count":0,"href":"https:\/\/www.squawka.com\/us-es\/wp-json\/wp\/v2\/player\/6563\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.squawka.com\/us-es\/wp-json\/wp\/v2\/media?parent=6563"}],"wp:term":[{"taxonomy":"season","embeddable":true,"href":"https:\/\/www.squawka.com\/us-es\/wp-json\/wp\/v2\/season?post=6563"},{"taxonomy":"sports-type","embeddable":true,"href":"https:\/\/www.squawka.com\/us-es\/wp-json\/wp\/v2\/sports-type?post=6563"},{"taxonomy":"country","embeddable":true,"href":"https:\/\/www.squawka.com\/us-es\/wp-json\/wp\/v2\/country?post=6563"},{"taxonomy":"event-competition","embeddable":true,"href":"https:\/\/www.squawka.com\/us-es\/wp-json\/wp\/v2\/event-competition?post=6563"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}